{"id":66482,"date":"2021-11-09T10:09:39","date_gmt":"2021-11-09T04:24:39","guid":{"rendered":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg"},"modified":"2021-11-09T10:10:11","modified_gmt":"2021-11-09T04:25:11","slug":"students-in-dandelion-middle-school-china","status":"inherit","type":"attachment","link":"https:\/\/leftreviewonline.com\/english\/opinion\/chinas-heavy-investment-education-lays-foundation-national-development.html\/attachment\/students-in-dandelion-middle-school-china","title":{"rendered":"Students-in-Dandelion-Middle-School-china"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Students-in-Dandelion-Middle-School-china - Left Review Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Students-in-Dandelion-Middle-School-china - Left Review Online\" \/>\n<meta property=\"og:description\" content=\"Students in Dandelion Middle School play on the playground. Photo: Li Hao\/Global Times\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Left Review Online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LeftReviewOnline\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-09T04:25:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg?fit=800%2C450&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@leftreviewnepal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg\",\"url\":\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg\",\"name\":\"Students-in-Dandelion-Middle-School-china - Left Review Online\",\"isPartOf\":{\"@id\":\"https:\/\/leftreviewonline.com\/english\/#website\"},\"datePublished\":\"2021-11-09T04:24:39+00:00\",\"dateModified\":\"2021-11-09T04:25:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/leftreviewonline.com\/english\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"China\u2019s heavy investment in education lays foundation for national development\",\"item\":\"https:\/\/leftreviewonline.com\/english\/opinion\/chinas-heavy-investment-education-lays-foundation-national-development.html\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Students-in-Dandelion-Middle-School-china\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/leftreviewonline.com\/english\/#website\",\"url\":\"https:\/\/leftreviewonline.com\/english\/\",\"name\":\"Left Review Online\",\"description\":\"Devoted for peace, progress, prosperity and socialism\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/leftreviewonline.com\/english\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Students-in-Dandelion-Middle-School-china - Left Review Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg","og_locale":"en_GB","og_type":"article","og_title":"Students-in-Dandelion-Middle-School-china - Left Review Online","og_description":"Students in Dandelion Middle School play on the playground. Photo: Li Hao\/Global Times","og_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg","og_site_name":"Left Review Online","article_publisher":"https:\/\/www.facebook.com\/LeftReviewOnline\/","article_modified_time":"2021-11-09T04:25:11+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/i0.wp.com\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg?fit=800%2C450&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@leftreviewnepal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg","url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg","name":"Students-in-Dandelion-Middle-School-china - Left Review Online","isPartOf":{"@id":"https:\/\/leftreviewonline.com\/english\/#website"},"datePublished":"2021-11-09T04:24:39+00:00","dateModified":"2021-11-09T04:25:11+00:00","breadcrumb":{"@id":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leftreviewonline.com\/english\/"},{"@type":"ListItem","position":2,"name":"China\u2019s heavy investment in education lays foundation for national development","item":"https:\/\/leftreviewonline.com\/english\/opinion\/chinas-heavy-investment-education-lays-foundation-national-development.html"},{"@type":"ListItem","position":3,"name":"Students-in-Dandelion-Middle-School-china"}]},{"@type":"WebSite","@id":"https:\/\/leftreviewonline.com\/english\/#website","url":"https:\/\/leftreviewonline.com\/english\/","name":"Left Review Online","description":"Devoted for peace, progress, prosperity and socialism","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leftreviewonline.com\/english\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"Students, Dandelion Middle School, playground.\" srcset=\"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-300x169.jpg 300w, https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-768x432.jpg 768w, https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-788x444.jpg 788w, https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg 800w\" sizes=\"100vw\" \/><\/a><\/p>\n<p>Students in Dandelion Middle School play on the playground. Photo: Li Hao\/Global Times<\/p>\n"},"caption":{"rendered":"<p>Students in Dandelion Middle School play on the playground. Photo: Li Hao\/Global Times<\/p>\n"},"alt_text":"Students, Dandelion Middle School, playground.","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":450,"file":"2021\/11\/Students-in-Dandelion-Middle-School-china.jpg","sizes":{"thumbnail":{"file":"Students-in-Dandelion-Middle-School-china-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-150x150.jpg"},"medium":{"file":"Students-in-Dandelion-Middle-School-china-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-300x169.jpg"},"medium_large":{"file":"Students-in-Dandelion-Middle-School-china-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-768x432.jpg"},"twentyseventeen-thumbnail-avatar":{"file":"Students-in-Dandelion-Middle-School-china-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-100x100.jpg"},"big-image":{"file":"Students-in-Dandelion-Middle-School-china-394x246.jpg","width":394,"height":246,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-394x246.jpg"},"slider-image":{"file":"Students-in-Dandelion-Middle-School-china-792x354.jpg","width":792,"height":354,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-792x354.jpg"},"slider-image-2":{"file":"Students-in-Dandelion-Middle-School-china-788x444.jpg","width":788,"height":444,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china-788x444.jpg"},"full":{"file":"Students-in-Dandelion-Middle-School-china.jpg","width":800,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":66481,"source_url":"https:\/\/leftreviewonline.com\/english\/wp-content\/uploads\/2021\/11\/Students-in-Dandelion-Middle-School-china.jpg","_links":{"self":[{"href":"https:\/\/leftreviewonline.com\/english\/wp-json\/wp\/v2\/media\/66482"}],"collection":[{"href":"https:\/\/leftreviewonline.com\/english\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/leftreviewonline.com\/english\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/leftreviewonline.com\/english\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leftreviewonline.com\/english\/wp-json\/wp\/v2\/comments?post=66482"}]}}